{"id":5944,"date":"2025-03-20T05:37:15","date_gmt":"2025-03-19T21:37:15","guid":{"rendered":"https:\/\/newworldhotels.com\/en\/gallery\/residence-club-deluxe-twin\/"},"modified":"2025-06-25T05:40:25","modified_gmt":"2025-06-24T21:40:25","slug":"residence-club-deluxe-twin","status":"publish","type":"portfolio_item","link":"https:\/\/newworldhotels.com\/sc\/gallery\/residence-club-deluxe-twin\/","title":{"rendered":"\u805a\u8d24\u835f\u8c6a\u534e\u53cc\u5e8a\u623f"},"content":{"rendered":"\n<pre id=\"tw-target-text\" class=\"wp-block-preformatted\"><\/pre>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":256764881,"featured_media":8483,"parent":0,"template":"","meta":{"_acf_changed":false,"_crdt_document":"","_wpzb_portfolio_video_type":"","_wpzb_portfolio_video_id":0,"_wpzb_portfolio_video_url":"","footnotes":""},"portfolio":[1683],"class_list":["post-5944","portfolio_item","type-portfolio_item","status-publish","has-post-thumbnail","hentry","portfolio-nwwhn-3-"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>\u805a\u8d24\u835f\u8c6a\u534e\u53cc\u5e8a\u623f - New World Hotels &amp; Resorts | Asia&#039;s Leading 5-Star Luxury Hotel Chain<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/newworldhotels.com\/en\/gallery\/residence-club-deluxe-twin\/\" \/>\n<meta property=\"og:locale\" content=\"zh_CN\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u805a\u8d24\u835f\u8c6a\u534e\u53cc\u5e8a\u623f\" \/>\n<meta property=\"og:url\" content=\"https:\/\/newworldhotels.com\/en\/gallery\/residence-club-deluxe-twin\/\" \/>\n<meta property=\"og:site_name\" content=\"New World Hotels &amp; Resorts | Asia&#039;s Leading 5-Star Luxury Hotel Chain\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-24T21:40:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/newworldhotels.com\/wp-content\/uploads\/2025\/03\/Residence-Club-Deluxe-Twin.jpg?fit=1961%2C1326&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1961\" \/>\n\t<meta property=\"og:image:height\" content=\"1326\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/newworldhotels.com\\\/en\\\/gallery\\\/residence-club-deluxe-twin\\\/\",\"url\":\"https:\\\/\\\/newworldhotels.com\\\/en\\\/gallery\\\/residence-club-deluxe-twin\\\/\",\"name\":\"\u805a\u8d24\u835f\u8c6a\u534e\u53cc\u5e8a\u623f - New World Hotels &amp; Resorts | Asia&#039;s Leading 5-Star Luxury Hotel Chain\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/newworldhotels.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/newworldhotels.com\\\/en\\\/gallery\\\/residence-club-deluxe-twin\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/newworldhotels.com\\\/en\\\/gallery\\\/residence-club-deluxe-twin\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/newworldhotels.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/Residence-Club-Deluxe-Twin.jpg?fit=1961%2C1326&ssl=1\",\"datePublished\":\"2025-03-19T21:37:15+00:00\",\"dateModified\":\"2025-06-24T21:40:25+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/newworldhotels.com\\\/en\\\/gallery\\\/residence-club-deluxe-twin\\\/#breadcrumb\"},\"inLanguage\":\"zh-Hans\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/newworldhotels.com\\\/en\\\/gallery\\\/residence-club-deluxe-twin\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"zh-Hans\",\"@id\":\"https:\\\/\\\/newworldhotels.com\\\/en\\\/gallery\\\/residence-club-deluxe-twin\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/newworldhotels.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/Residence-Club-Deluxe-Twin.jpg?fit=1961%2C1326&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/newworldhotels.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/Residence-Club-Deluxe-Twin.jpg?fit=1961%2C1326&ssl=1\",\"width\":1961,\"height\":1326},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/newworldhotels.com\\\/en\\\/gallery\\\/residence-club-deluxe-twin\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/newworldhotels.com\\\/sc\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Portfolio\",\"item\":\"https:\\\/\\\/newworldhotels.com\\\/sc\\\/gallery\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u805a\u8d24\u835f\u8c6a\u534e\u53cc\u5e8a\u623f\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/newworldhotels.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/newworldhotels.com\\\/en\\\/\",\"name\":\"New World Hotels &amp; Resorts | Asia&#039;s Leading 5-Star Luxury Hotel Chain\",\"description\":\"Your Gateway to Unforgettable Business and Leisure Experiences in Asia\",\"publisher\":{\"@id\":\"https:\\\/\\\/newworldhotels.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/newworldhotels.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"zh-Hans\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/newworldhotels.com\\\/en\\\/#organization\",\"name\":\"New World Hotels &amp; Resorts | Asia&#039;s Leading 5-Star Luxury Hotel Chain\",\"url\":\"https:\\\/\\\/newworldhotels.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"zh-Hans\",\"@id\":\"https:\\\/\\\/newworldhotels.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/newworldhotels.com\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/nwh-brandsite-logo-en.png?fit=370%2C172&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/newworldhotels.com\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/nwh-brandsite-logo-en.png?fit=370%2C172&ssl=1\",\"width\":370,\"height\":172,\"caption\":\"New World Hotels &amp; Resorts | Asia&#039;s Leading 5-Star Luxury Hotel Chain\"},\"image\":{\"@id\":\"https:\\\/\\\/newworldhotels.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u805a\u8d24\u835f\u8c6a\u534e\u53cc\u5e8a\u623f - New World Hotels &amp; Resorts | Asia&#039;s Leading 5-Star Luxury Hotel Chain","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/newworldhotels.com\/en\/gallery\/residence-club-deluxe-twin\/","og_locale":"zh_CN","og_type":"article","og_title":"\u805a\u8d24\u835f\u8c6a\u534e\u53cc\u5e8a\u623f","og_url":"https:\/\/newworldhotels.com\/en\/gallery\/residence-club-deluxe-twin\/","og_site_name":"New World Hotels &amp; Resorts | Asia&#039;s Leading 5-Star Luxury Hotel Chain","article_modified_time":"2025-06-24T21:40:25+00:00","og_image":[{"width":1961,"height":1326,"url":"https:\/\/i0.wp.com\/newworldhotels.com\/wp-content\/uploads\/2025\/03\/Residence-Club-Deluxe-Twin.jpg?fit=1961%2C1326&ssl=1","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/newworldhotels.com\/en\/gallery\/residence-club-deluxe-twin\/","url":"https:\/\/newworldhotels.com\/en\/gallery\/residence-club-deluxe-twin\/","name":"\u805a\u8d24\u835f\u8c6a\u534e\u53cc\u5e8a\u623f - New World Hotels &amp; Resorts | Asia&#039;s Leading 5-Star Luxury Hotel Chain","isPartOf":{"@id":"https:\/\/newworldhotels.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/newworldhotels.com\/en\/gallery\/residence-club-deluxe-twin\/#primaryimage"},"image":{"@id":"https:\/\/newworldhotels.com\/en\/gallery\/residence-club-deluxe-twin\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/newworldhotels.com\/wp-content\/uploads\/2025\/03\/Residence-Club-Deluxe-Twin.jpg?fit=1961%2C1326&ssl=1","datePublished":"2025-03-19T21:37:15+00:00","dateModified":"2025-06-24T21:40:25+00:00","breadcrumb":{"@id":"https:\/\/newworldhotels.com\/en\/gallery\/residence-club-deluxe-twin\/#breadcrumb"},"inLanguage":"zh-Hans","potentialAction":[{"@type":"ReadAction","target":["https:\/\/newworldhotels.com\/en\/gallery\/residence-club-deluxe-twin\/"]}]},{"@type":"ImageObject","inLanguage":"zh-Hans","@id":"https:\/\/newworldhotels.com\/en\/gallery\/residence-club-deluxe-twin\/#primaryimage","url":"https:\/\/i0.wp.com\/newworldhotels.com\/wp-content\/uploads\/2025\/03\/Residence-Club-Deluxe-Twin.jpg?fit=1961%2C1326&ssl=1","contentUrl":"https:\/\/i0.wp.com\/newworldhotels.com\/wp-content\/uploads\/2025\/03\/Residence-Club-Deluxe-Twin.jpg?fit=1961%2C1326&ssl=1","width":1961,"height":1326},{"@type":"BreadcrumbList","@id":"https:\/\/newworldhotels.com\/en\/gallery\/residence-club-deluxe-twin\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/newworldhotels.com\/sc\/"},{"@type":"ListItem","position":2,"name":"Portfolio","item":"https:\/\/newworldhotels.com\/sc\/gallery\/"},{"@type":"ListItem","position":3,"name":"\u805a\u8d24\u835f\u8c6a\u534e\u53cc\u5e8a\u623f"}]},{"@type":"WebSite","@id":"https:\/\/newworldhotels.com\/en\/#website","url":"https:\/\/newworldhotels.com\/en\/","name":"New World Hotels &amp; Resorts | Asia&#039;s Leading 5-Star Luxury Hotel Chain","description":"Your Gateway to Unforgettable Business and Leisure Experiences in Asia","publisher":{"@id":"https:\/\/newworldhotels.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/newworldhotels.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"zh-Hans"},{"@type":"Organization","@id":"https:\/\/newworldhotels.com\/en\/#organization","name":"New World Hotels &amp; Resorts | Asia&#039;s Leading 5-Star Luxury Hotel Chain","url":"https:\/\/newworldhotels.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"zh-Hans","@id":"https:\/\/newworldhotels.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/newworldhotels.com\/wp-content\/uploads\/2025\/02\/nwh-brandsite-logo-en.png?fit=370%2C172&ssl=1","contentUrl":"https:\/\/i0.wp.com\/newworldhotels.com\/wp-content\/uploads\/2025\/02\/nwh-brandsite-logo-en.png?fit=370%2C172&ssl=1","width":370,"height":172,"caption":"New World Hotels &amp; Resorts | Asia&#039;s Leading 5-Star Luxury Hotel Chain"},"image":{"@id":"https:\/\/newworldhotels.com\/en\/#\/schema\/logo\/image\/"}}]}},"jetpack_sharing_enabled":true,"featured_media_urls":{"thumbnail":["https:\/\/i0.wp.com\/newworldhotels.com\/wp-content\/uploads\/2025\/03\/Residence-Club-Deluxe-Twin.jpg?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/newworldhotels.com\/wp-content\/uploads\/2025\/03\/Residence-Club-Deluxe-Twin.jpg?fit=300%2C203&ssl=1",300,203,true],"medium_large":["https:\/\/i0.wp.com\/newworldhotels.com\/wp-content\/uploads\/2025\/03\/Residence-Club-Deluxe-Twin.jpg?fit=768%2C519&ssl=1",768,519,true],"large":["https:\/\/i0.wp.com\/newworldhotels.com\/wp-content\/uploads\/2025\/03\/Residence-Club-Deluxe-Twin.jpg?fit=950%2C642&ssl=1",950,642,true],"1536x1536":["https:\/\/i0.wp.com\/newworldhotels.com\/wp-content\/uploads\/2025\/03\/Residence-Club-Deluxe-Twin.jpg?fit=1536%2C1039&ssl=1",1536,1039,true],"2048x2048":["https:\/\/i0.wp.com\/newworldhotels.com\/wp-content\/uploads\/2025\/03\/Residence-Club-Deluxe-Twin.jpg?fit=1961%2C1326&ssl=1",1961,1326,true],"newspack-article-block-landscape-large":["https:\/\/i0.wp.com\/newworldhotels.com\/wp-content\/uploads\/2025\/03\/Residence-Club-Deluxe-Twin.jpg?resize=1200%2C900&ssl=1",1200,900,true],"newspack-article-block-portrait-large":["https:\/\/i0.wp.com\/newworldhotels.com\/wp-content\/uploads\/2025\/03\/Residence-Club-Deluxe-Twin.jpg?resize=900%2C1200&ssl=1",900,1200,true],"newspack-article-block-square-large":["https:\/\/i0.wp.com\/newworldhotels.com\/wp-content\/uploads\/2025\/03\/Residence-Club-Deluxe-Twin.jpg?resize=1200%2C1200&ssl=1",1200,1200,true],"newspack-article-block-landscape-medium":["https:\/\/i0.wp.com\/newworldhotels.com\/wp-content\/uploads\/2025\/03\/Residence-Club-Deluxe-Twin.jpg?resize=800%2C600&ssl=1",800,600,true],"newspack-article-block-portrait-medium":["https:\/\/i0.wp.com\/newworldhotels.com\/wp-content\/uploads\/2025\/03\/Residence-Club-Deluxe-Twin.jpg?resize=600%2C800&ssl=1",600,800,true],"newspack-article-block-square-medium":["https:\/\/i0.wp.com\/newworldhotels.com\/wp-content\/uploads\/2025\/03\/Residence-Club-Deluxe-Twin.jpg?resize=800%2C800&ssl=1",800,800,true],"newspack-article-block-landscape-intermediate":["https:\/\/i0.wp.com\/newworldhotels.com\/wp-content\/uploads\/2025\/03\/Residence-Club-Deluxe-Twin.jpg?resize=600%2C450&ssl=1",600,450,true],"newspack-article-block-portrait-intermediate":["https:\/\/i0.wp.com\/newworldhotels.com\/wp-content\/uploads\/2025\/03\/Residence-Club-Deluxe-Twin.jpg?resize=450%2C600&ssl=1",450,600,true],"newspack-article-block-square-intermediate":["https:\/\/i0.wp.com\/newworldhotels.com\/wp-content\/uploads\/2025\/03\/Residence-Club-Deluxe-Twin.jpg?resize=600%2C600&ssl=1",600,600,true],"newspack-article-block-landscape-small":["https:\/\/i0.wp.com\/newworldhotels.com\/wp-content\/uploads\/2025\/03\/Residence-Club-Deluxe-Twin.jpg?resize=400%2C300&ssl=1",400,300,true],"newspack-article-block-portrait-small":["https:\/\/i0.wp.com\/newworldhotels.com\/wp-content\/uploads\/2025\/03\/Residence-Club-Deluxe-Twin.jpg?resize=300%2C400&ssl=1",300,400,true],"newspack-article-block-square-small":["https:\/\/i0.wp.com\/newworldhotels.com\/wp-content\/uploads\/2025\/03\/Residence-Club-Deluxe-Twin.jpg?resize=400%2C400&ssl=1",400,400,true],"newspack-article-block-landscape-tiny":["https:\/\/i0.wp.com\/newworldhotels.com\/wp-content\/uploads\/2025\/03\/Residence-Club-Deluxe-Twin.jpg?resize=200%2C150&ssl=1",200,150,true],"newspack-article-block-portrait-tiny":["https:\/\/i0.wp.com\/newworldhotels.com\/wp-content\/uploads\/2025\/03\/Residence-Club-Deluxe-Twin.jpg?resize=150%2C200&ssl=1",150,200,true],"newspack-article-block-square-tiny":["https:\/\/i0.wp.com\/newworldhotels.com\/wp-content\/uploads\/2025\/03\/Residence-Club-Deluxe-Twin.jpg?resize=200%2C200&ssl=1",200,200,true],"newspack-article-block-uncropped":["https:\/\/i0.wp.com\/newworldhotels.com\/wp-content\/uploads\/2025\/03\/Residence-Club-Deluxe-Twin.jpg?fit=1200%2C811&ssl=1",1200,811,true],"inspiro-featured-image":["https:\/\/i0.wp.com\/newworldhotels.com\/wp-content\/uploads\/2025\/03\/Residence-Club-Deluxe-Twin.jpg?fit=1961%2C1326&ssl=1",1961,1326,true],"inspiro-loop":["https:\/\/i0.wp.com\/newworldhotels.com\/wp-content\/uploads\/2025\/03\/Residence-Club-Deluxe-Twin.jpg?resize=950%2C320&ssl=1",950,320,true],"inspiro-loop@2x":["https:\/\/i0.wp.com\/newworldhotels.com\/wp-content\/uploads\/2025\/03\/Residence-Club-Deluxe-Twin.jpg?resize=1900%2C640&ssl=1",1900,640,true],"portfolio_item-thumbnail":["https:\/\/i0.wp.com\/newworldhotels.com\/wp-content\/uploads\/2025\/03\/Residence-Club-Deluxe-Twin.jpg?resize=600%2C400&ssl=1",600,400,true],"portfolio_item-thumbnail@2x":["https:\/\/i0.wp.com\/newworldhotels.com\/wp-content\/uploads\/2025\/03\/Residence-Club-Deluxe-Twin.jpg?resize=1200%2C800&ssl=1",1200,800,true],"portfolio_item-masonry":["https:\/\/i0.wp.com\/newworldhotels.com\/wp-content\/uploads\/2025\/03\/Residence-Club-Deluxe-Twin.jpg?fit=600%2C406&ssl=1",600,406,true],"portfolio_item-masonry@2x":["https:\/\/i0.wp.com\/newworldhotels.com\/wp-content\/uploads\/2025\/03\/Residence-Club-Deluxe-Twin.jpg?fit=1200%2C811&ssl=1",1200,811,true],"portfolio_item-thumbnail_cinema":["https:\/\/i0.wp.com\/newworldhotels.com\/wp-content\/uploads\/2025\/03\/Residence-Club-Deluxe-Twin.jpg?resize=800%2C335&ssl=1",800,335,true],"portfolio_item-thumbnail_portrait":["https:\/\/i0.wp.com\/newworldhotels.com\/wp-content\/uploads\/2025\/03\/Residence-Club-Deluxe-Twin.jpg?resize=600%2C900&ssl=1",600,900,true],"portfolio_item-thumbnail_portrait@2x":["https:\/\/i0.wp.com\/newworldhotels.com\/wp-content\/uploads\/2025\/03\/Residence-Club-Deluxe-Twin.jpg?resize=1200%2C1326&ssl=1",1200,1326,true],"portfolio_item-thumbnail_square":["https:\/\/i0.wp.com\/newworldhotels.com\/wp-content\/uploads\/2025\/03\/Residence-Club-Deluxe-Twin.jpg?resize=800%2C800&ssl=1",800,800,true]},"_links":{"self":[{"href":"https:\/\/newworldhotels.com\/sc\/wp-json\/wp\/v2\/portfolio_item\/5944","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/newworldhotels.com\/sc\/wp-json\/wp\/v2\/portfolio_item"}],"about":[{"href":"https:\/\/newworldhotels.com\/sc\/wp-json\/wp\/v2\/types\/portfolio_item"}],"author":[{"embeddable":true,"href":"https:\/\/newworldhotels.com\/sc\/wp-json\/wp\/v2\/users\/256764881"}],"version-history":[{"count":1,"href":"https:\/\/newworldhotels.com\/sc\/wp-json\/wp\/v2\/portfolio_item\/5944\/revisions"}],"predecessor-version":[{"id":5962,"href":"https:\/\/newworldhotels.com\/sc\/wp-json\/wp\/v2\/portfolio_item\/5944\/revisions\/5962"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/newworldhotels.com\/sc\/wp-json\/wp\/v2\/media\/8483"}],"wp:attachment":[{"href":"https:\/\/newworldhotels.com\/sc\/wp-json\/wp\/v2\/media?parent=5944"}],"wp:term":[{"taxonomy":"portfolio","embeddable":true,"href":"https:\/\/newworldhotels.com\/sc\/wp-json\/wp\/v2\/portfolio?post=5944"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}